{"id":8654,"date":"2025-02-07T12:50:00","date_gmt":"2025-02-07T15:50:00","guid":{"rendered":"https:\/\/involves.com\/?p=8654"},"modified":"2025-09-12T17:12:56","modified_gmt":"2025-09-12T20:12:56","slug":"involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing","status":"publish","type":"post","link":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/","title":{"rendered":"Involves, o SaaS do trade marketing, capta e compra startup chilena"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Involves \u2014 que desenvolve software para trade marketing \u2014 levantou recentemente <strong>R$ 70 milh\u00f5es em uma rodada de investimentos<\/strong> destinada principalmente \u00e0 aquisi\u00e7\u00e3o de um concorrente chileno. A capta\u00e7\u00e3o foi realizada pela Bridge One, que j\u00e1 havia investido anteriormente na Involves e \u00e9 o \u00fanico fundo presente no cap table da startup brasileira.<br><br>Fundada em Florian\u00f3polis h\u00e1 16 anos, a Involves atua como um assistente para promotores de venda, auxiliando-os a executar suas tarefas com mais efici\u00eancia. O software da empresa permite que os promotores consultem seus roteiros de visita atrav\u00e9s de um aplicativo e analisem as metas de cada visita \u2014 como aumentar a participa\u00e7\u00e3o nas g\u00f4ndolas, ajustar pre\u00e7os dos produtos, adicionar pontos extras ou incluir novos materiais de merchandising.<br>Ap\u00f3s a conclus\u00e3o do trabalho, o promotor captura fotos das g\u00f4ndolas e as envia para a plataforma da Involves, que utiliza vis\u00e3o computacional para transformar essas imagens em dados. &#8220;<em>Com esses dados, atribu\u00edmos uma nota para a visita, proporcionando ao promotor uma vis\u00e3o sobre a qualidade da execu\u00e7\u00e3o e indicando \u00e1reas de melhoria<\/em>&#8220;, explicou Andr\u00e9 Krummenauer, fundador da Involves.<br><br>Os recursos obtidos na rodada ser\u00e3o utilizados para a aquisi\u00e7\u00e3o da <strong>Datamind \u2014 uma startup chilena que opera em 18 pa\u00edses da Am\u00e9rica Latina, com receita majoritariamente proveniente do M\u00e9xico<\/strong>. Embora o valor da aquisi\u00e7\u00e3o n\u00e3o tenha sido divulgado, Andr\u00e9 mencionou que mais da metade do montante captado ser\u00e1 destinado ao M&amp;A.<br><br>A Datamind gera aproximadamente R$ 13 milh\u00f5es em receita, que ser\u00e3o adicionados aos R$ 127 milh\u00f5es faturados pela Involves no ano anterior, atendendo clientes como L\u2019Or\u00e9al, Kraft Heinz, Unilever e Pepsico. H\u00e1 uma clara complementaridade entre as duas empresas: <strong>enquanto a Involves foca na execu\u00e7\u00e3o das estrat\u00e9gias de trade marketing, a Datamind atua na otimiza\u00e7\u00e3o, fornecendo dados de vendas e estoque de varejistas em mais de 18 pa\u00edses<\/strong>. Isso permitir\u00e1 correlacionar a execu\u00e7\u00e3o com os resultados e oferecer sugest\u00f5es de melhoria.<br><br>A aquisi\u00e7\u00e3o tamb\u00e9m refor\u00e7a a <strong>estrat\u00e9gia de internacionaliza\u00e7\u00e3o da Involves<\/strong>, que j\u00e1 est\u00e1 presente em 24 pa\u00edses, muitas vezes atrav\u00e9s de clientes multinacionais que adotaram sua solu\u00e7\u00e3o em outras regi\u00f5es. Em termos de receita, o M\u00e9xico \u00e9 o segundo maior mercado da empresa, atr\u00e1s apenas do Brasil.<br><br>&#8220;<em>A uni\u00e3o das duas solu\u00e7\u00f5es cria uma proposta muito forte. A Datamind sabe o que est\u00e1 e o que n\u00e3o est\u00e1 vendendo, mas entre ter esse dado e agir sobre ele h\u00e1 uma grande dist\u00e2ncia<\/em>&#8220;, afirmou Andr\u00e9. &#8220;<em>Com a Involves, conseguimos fechar esse ciclo, transformando dados em a\u00e7\u00f5es concretas para melhorar os resultados.<\/em>&#8220;<br><br>A estrat\u00e9gia de aquisi\u00e7\u00f5es tem se mostrado eficaz para a Involves, que conseguiu aumentar a receita de todas as empresas adquiridas. &#8220;<em>Com a Stringhini, por exemplo, levamos a receita de zero a 25% do nosso ARR muito rapidamente<\/em>&#8220;, destacou o fundador. O plano \u00e9 realizar mais tr\u00eas ou quatro aquisi\u00e7\u00f5es nos pr\u00f3ximos tr\u00eas anos, sendo que uma delas j\u00e1 est\u00e1 em andamento. <strong>A vis\u00e3o para os pr\u00f3ximos cinco anos \u00e9 alcan\u00e7ar uma receita de R$ 350 milh\u00f5es, com 30% provenientes de mercados fora do Brasil.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a aquisi\u00e7\u00e3o da Datamind, a atua\u00e7\u00e3o na Am\u00e9rica Latina se expande, e as solu\u00e7\u00f5es para trade marketing ficam ainda mais robustas.<\/p>\n","protected":false},"author":2,"featured_media":8823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-8654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-midia-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Involves, o SaaS do trade marketing, capta e compra startup chilena - Involves<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Involves, o SaaS do trade marketing, capta e compra startup chilena - Involves\" \/>\n<meta property=\"og:description\" content=\"Com a aquisi\u00e7\u00e3o da Datamind, a atua\u00e7\u00e3o na Am\u00e9rica Latina se expande, e as solu\u00e7\u00f5es para trade marketing ficam ainda mais robustas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"Involves\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-07T15:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-12T20:12:56+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/involves.com\/wp-content\/uploads\/2025\/02\/image-20.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1808\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Jonas Nascimento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jonas Nascimento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/\"},\"author\":{\"name\":\"Jonas Nascimento\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/897f3c0868ab928fa091aabef380b6b0\"},\"headline\":\"Involves, o SaaS do trade marketing, capta e compra startup chilena\",\"datePublished\":\"2025-02-07T15:50:00+00:00\",\"dateModified\":\"2025-09-12T20:12:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/\"},\"wordCount\":553,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-20.webp\",\"articleSection\":[\"midia-pt\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/\",\"url\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/\",\"name\":\"Involves, o SaaS do trade marketing, capta e compra startup chilena - Involves\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-20.webp\",\"datePublished\":\"2025-02-07T15:50:00+00:00\",\"dateModified\":\"2025-09-12T20:12:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-20.webp\",\"contentUrl\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-20.webp\",\"width\":1808,\"height\":945,\"caption\":\"Involves antecipa as tend\u00eancias de IA e automa\u00e7\u00e3o para 2025 no trade\u00a0marketing\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/midia-pt\\\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Involves, o SaaS do trade marketing, capta e compra startup chilena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/\",\"name\":\"Involves\",\"description\":\"Involves: com nosso software de Trade voc\u00ea acerta o tom da execu\u00e7\u00e3o, aumenta a batida do sell-out e afina a produtividade da sua equipe\",\"publisher\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#organization\",\"name\":\"Involves\",\"url\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/involves-logo-preto.webp\",\"contentUrl\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/involves-logo-preto.webp\",\"width\":532,\"height\":112,\"caption\":\"Involves\"},\"image\":{\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/#\\\/schema\\\/person\\\/897f3c0868ab928fa091aabef380b6b0\",\"name\":\"Jonas Nascimento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/litespeed\\\/avatar\\\/54a2dee754e39037942cd8b92279a7b1.jpg?ver=1787780598\",\"url\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/litespeed\\\/avatar\\\/54a2dee754e39037942cd8b92279a7b1.jpg?ver=1787780598\",\"contentUrl\":\"https:\\\/\\\/involves.com\\\/wp-content\\\/litespeed\\\/avatar\\\/54a2dee754e39037942cd8b92279a7b1.jpg?ver=1787780598\",\"caption\":\"Jonas Nascimento\"},\"url\":\"https:\\\/\\\/involves.com\\\/pt-br\\\/author\\\/jonas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Involves, o SaaS do trade marketing, capta e compra startup chilena - Involves","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"pt_BR","og_type":"article","og_title":"Involves, o SaaS do trade marketing, capta e compra startup chilena - Involves","og_description":"Com a aquisi\u00e7\u00e3o da Datamind, a atua\u00e7\u00e3o na Am\u00e9rica Latina se expande, e as solu\u00e7\u00f5es para trade marketing ficam ainda mais robustas.","og_url":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/","og_site_name":"Involves","article_published_time":"2025-02-07T15:50:00+00:00","article_modified_time":"2025-09-12T20:12:56+00:00","og_image":[{"width":1808,"height":945,"url":"http:\/\/involves.com\/wp-content\/uploads\/2025\/02\/image-20.webp","type":"image\/webp"}],"author":"Jonas Nascimento","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jonas Nascimento","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#article","isPartOf":{"@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/"},"author":{"name":"Jonas Nascimento","@id":"https:\/\/involves.com\/pt-br\/#\/schema\/person\/897f3c0868ab928fa091aabef380b6b0"},"headline":"Involves, o SaaS do trade marketing, capta e compra startup chilena","datePublished":"2025-02-07T15:50:00+00:00","dateModified":"2025-09-12T20:12:56+00:00","mainEntityOfPage":{"@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/"},"wordCount":553,"commentCount":0,"publisher":{"@id":"https:\/\/involves.com\/pt-br\/#organization"},"image":{"@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#primaryimage"},"thumbnailUrl":"https:\/\/involves.com\/wp-content\/uploads\/2025\/02\/image-20.webp","articleSection":["midia-pt"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/","url":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/","name":"Involves, o SaaS do trade marketing, capta e compra startup chilena - Involves","isPartOf":{"@id":"https:\/\/involves.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#primaryimage"},"image":{"@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#primaryimage"},"thumbnailUrl":"https:\/\/involves.com\/wp-content\/uploads\/2025\/02\/image-20.webp","datePublished":"2025-02-07T15:50:00+00:00","dateModified":"2025-09-12T20:12:56+00:00","breadcrumb":{"@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#primaryimage","url":"https:\/\/involves.com\/wp-content\/uploads\/2025\/02\/image-20.webp","contentUrl":"https:\/\/involves.com\/wp-content\/uploads\/2025\/02\/image-20.webp","width":1808,"height":945,"caption":"Involves antecipa as tend\u00eancias de IA e automa\u00e7\u00e3o para 2025 no trade\u00a0marketing"},{"@type":"BreadcrumbList","@id":"https:\/\/involves.com\/pt-br\/midia-pt\/involves-cresce-e-adquire-startup-chilena-de-tecnologia-para-trade-marketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/involves.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Involves, o SaaS do trade marketing, capta e compra startup chilena"}]},{"@type":"WebSite","@id":"https:\/\/involves.com\/pt-br\/#website","url":"https:\/\/involves.com\/pt-br\/","name":"Involves","description":"Involves: com nosso software de Trade voc\u00ea acerta o tom da execu\u00e7\u00e3o, aumenta a batida do sell-out e afina a produtividade da sua equipe","publisher":{"@id":"https:\/\/involves.com\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/involves.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/involves.com\/pt-br\/#organization","name":"Involves","url":"https:\/\/involves.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/involves.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/involves.com\/wp-content\/uploads\/2024\/12\/involves-logo-preto.webp","contentUrl":"https:\/\/involves.com\/wp-content\/uploads\/2024\/12\/involves-logo-preto.webp","width":532,"height":112,"caption":"Involves"},"image":{"@id":"https:\/\/involves.com\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/involves.com\/pt-br\/#\/schema\/person\/897f3c0868ab928fa091aabef380b6b0","name":"Jonas Nascimento","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/involves.com\/wp-content\/litespeed\/avatar\/54a2dee754e39037942cd8b92279a7b1.jpg?ver=1787780598","url":"https:\/\/involves.com\/wp-content\/litespeed\/avatar\/54a2dee754e39037942cd8b92279a7b1.jpg?ver=1787780598","contentUrl":"https:\/\/involves.com\/wp-content\/litespeed\/avatar\/54a2dee754e39037942cd8b92279a7b1.jpg?ver=1787780598","caption":"Jonas Nascimento"},"url":"https:\/\/involves.com\/pt-br\/author\/jonas\/"}]}},"_links":{"self":[{"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/posts\/8654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/comments?post=8654"}],"version-history":[{"count":18,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/posts\/8654\/revisions"}],"predecessor-version":[{"id":12403,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/posts\/8654\/revisions\/12403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/media\/8823"}],"wp:attachment":[{"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/media?parent=8654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/categories?post=8654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/involves.com\/pt-br\/wp-json\/wp\/v2\/tags?post=8654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}